{"id":5624,"date":"2025-03-26T18:04:00","date_gmt":"2025-03-26T17:04:00","guid":{"rendered":"https:\/\/lesboitesdebobonne.com\/?post_type=product&#038;p=5624"},"modified":"2026-01-11T12:09:52","modified_gmt":"2026-01-11T11:09:52","slug":"fish-lover","status":"publish","type":"product","link":"https:\/\/lesboitesdebobonne.com\/index.php\/produit\/fish-lover\/","title":{"rendered":"Fish lover"},"content":{"rendered":"<p class=\"whitespace-pre-wrap break-words\">\ud83d\udc1f LA BOX POISSON \u2013 BY CHEFFE BOBONNETTE<\/p>\n<p class=\"whitespace-pre-wrap break-words\"><strong>Envie d&rsquo;une pause marine, gourmande et pleine de saveurs ?<\/strong> Laissez-vous tenter par notre box poisson &amp; v\u00e9g\u00e9, pens\u00e9e pour ceux qui aiment se r\u00e9galer avec des tr\u00e9sors de la mer, <strong>beaucoup d&rsquo;amour, de cr\u00e9ativit\u00e9\u2026 et une pinc\u00e9e d&rsquo;humour !<\/strong> \ud83c\udf0a<\/p>\n<p class=\"whitespace-pre-wrap break-words\">\ud83c\udf1e AU MENU : FRA\u00ceCHEUR, OC\u00c9AN &amp; GOOD VIBES Ici, chaque bouch\u00e9e est un voyage en haute mer. Cheffe Bobonnette imagine de nouvelles recettes de poissons ultra gourmandes, inspir\u00e9es des produits frais, de la saison\u2026 et de ses d\u00e9lires culinaires !<br \/>\nUn m\u00e9lange parfait de <strong>fra\u00eecheur marine<\/strong>, de <strong>bonne humeur<\/strong> et de <strong>plaisir sans compromis<\/strong>.<\/p>\n<p class=\"whitespace-pre-wrap break-words\">\ud83d\udce6 <em>Dispo en version ap\u00e9ro (sal\u00e9) ou brunch (sucr\u00e9-sal\u00e9)<\/em><\/p>\n<p class=\"whitespace-pre-wrap break-words\">\ud83d\udc20 CE QUI VOUS ATTEND DANS VOTRE BOX :<\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\"><strong>Des recettes pleines de peps<\/strong> : tartare de poisson, quiches marines, verrines de la mer, rolls de saumon, mini-cakes aux fruits de mer, bouch\u00e9es de v\u00e9g\u00e9tariennes\u2026<\/li>\n<li class=\"whitespace-normal break-words\"><strong>Z\u00e9ro routine, z\u00e9ro ennui<\/strong> : le contenu change tous les mois selon l&rsquo;inspiration de Bobonnette et les produits de saison.<\/li>\n<li class=\"whitespace-normal break-words\"><strong>Une touche de folie<\/strong> : parce que manger du poisson, c&rsquo;est aussi se faire plaisir, rire, partager, et d\u00e9couvrir.<\/li>\n<\/ul>\n<p class=\"whitespace-pre-wrap break-words\">\ud83e\udd90 EXEMPLES DE PETITS BONHEURS MARINS :<\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Mini quiches au saumon et aneth<\/li>\n<li class=\"whitespace-normal break-words\">Pissaladi\u00e8re aux anchois<\/li>\n<li class=\"whitespace-normal break-words\">Brochettes tomates mozza marin\u00e9es<\/li>\n<li class=\"whitespace-normal break-words\">Navettes gourmettes au saumon fum\u00e9<\/li>\n<li class=\"whitespace-normal break-words\">Olives marin\u00e9es<\/li>\n<li class=\"whitespace-normal break-words\">Wraps de thon cr\u00e9meux<\/li>\n<li class=\"whitespace-normal break-words\">Bouch\u00e9es feuillet\u00e9es au fromage<\/li>\n<\/ul>\n<p class=\"whitespace-pre-wrap break-words\"><em>Le contenu exact reste une surprise\u2026 mais vos papilles navigueront avec bonheur !<\/em> \ud83e\udd2b<\/p>\n<h3 class=\"\" data-start=\"584\" data-end=\"652\"><strong data-start=\"591\" data-end=\"650\">\ud83d\udce6Formats disponibles<\/strong><\/h3>\n<ul data-start=\"1939\" data-end=\"2200\">\n<li class=\"\" data-start=\"1939\" data-end=\"2046\">\n<p class=\"\" data-start=\"1941\" data-end=\"2046\"><strong data-start=\"1941\" data-end=\"1949\">MAXI<\/strong> \u2013 54\u20ac<br data-start=\"1955\" data-end=\"1958\" \/>\ud83d\udc49 Repas principal pour 2\u00a0 adultes gourmands<\/p>\n<\/li>\n<li class=\"\" data-start=\"2048\" data-end=\"2130\">\n<p class=\"\" data-start=\"2050\" data-end=\"2130\"><strong data-start=\"2050\" data-end=\"2058\">MINI<\/strong> \u2013 30\u20ac<br data-start=\"2064\" data-end=\"2067\" \/>\ud83d\udc49 Repas complet pour 1 adulte<\/p>\n<\/li>\n<li class=\"\" data-start=\"2132\" data-end=\"2200\">\n<p class=\"\" data-start=\"2134\" data-end=\"2200\"><strong data-start=\"2134\" data-end=\"2142\">BABY<\/strong> \u2013 15\u20ac<br data-start=\"2148\" data-end=\"2151\" \/>\ud83d\udc49 Format adapt\u00e9 pour un enfant de 3 \u00e0 12 ans<\/p>\n<\/li>\n<\/ul>\n<hr class=\"\" data-start=\"2194\" data-end=\"2197\" \/>\n<h3 class=\"\" data-start=\"2199\" data-end=\"2224\">\ud83c\udf81 PR\u00caT\u00b7E \u00c0 CRAQUER ?<\/h3>\n<p class=\"\" data-start=\"2226\" data-end=\"2348\">Offrez-vous (ou \u00e0 vos proches) une pause v\u00e9g\u00e9tarienne joyeuse, savoureuse et pleine de surprises sign\u00e9e Cheffe Bobonnette.<\/p>\n<p><strong><b>JE VOUS EXPLIQUE EN VID\u00c9O?<br \/>\n<\/b><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"220\" data-end=\"268\"><span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\ud83d\udc1fLa box qui dit non \u00e0 la viande, oui au poisson et aux l\u00e9gumes!<\/span><\/span><\/p>\n","protected":false},"featured_media":5625,"template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\ud83c\udf7e<\/span><\/span>D\u00e9licieuses gougouilles sal\u00e9es \u00e0 partager avec en plus, des nouveaut\u00e9s et surprises chaque mois<span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\ud83e\udd42<\/span><\/span>\r\n\r\n<span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\ud83d\ude0d\r\n<\/span><\/span>La composition de votre box varie en fonction des saisons et de l\u2019humeur de cheffe Bobonnette.Voici des exemples de ce que vous pouvez retrouver dans votre box ap\u00e9ro:\r\nCakes sal\u00e9s \u00a0|\u00a0 Trempettes\u00a0 |\u00a0 Chichen wings \u00a0|\u00a0 Olives marin\u00e9es \u00a0|\u00a0 Velout\u00e9 du moment \u00a0|\u00a0 Mini quiches maison \u00a0|\u00a0 Samoussas \u00a0|\u00a0 Mini boulettes | Wraps | Pissaladi\u00e8re\u00a0 |\u00a0 Boudin blanc grill\u00e9 | Bruschetta | Mini lasagne | Ribs caramelis\u00e9s | Fromage \u00a0|\u00a0 Charcuteries \u00a0|\u00a0 L\u00e9gumes croquants | Tapenades | Mini gratin | Mini pizza...\r\n\r\n<span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\u2753\r\n<\/span><\/span>Vous ne savez donc pas \u00e0 100% ce qu\u2019il y aura dedans mais soyez certains que ce sera d\u00e9licieux et pr\u00e9par\u00e9 avec Amour.\r\nDisponible pour r\u00e9gime sp\u00e9cial.\r\n\r\n<strong><b>FORMATS \u00a0DISPONIBLES\r\n<\/b><\/strong>\u2022MAXI\u00a0 \u00a0 \u00a0|\u00a0 \u00a0 \u00a054\u20ac\u00a0 \u00a0 \u00a0 |\u00a0 \u00a0 \u00a0Repas principal pour 2\/3 adultes gourmands ou comme ap\u00e9ro avant un autre repas pour 4\/6 adultes\r\n\u2022MINI\u00a0 \u00a0 \u00a0 |\u00a0 \u00a0 \u00a030\u20ac\u00a0 \u00a0 \u00a0 |\u00a0 \u00a0 \u00a0 Repas principal pour 1 adulte ou pour grignoter avant un autre repas pour 2\/3 adultes\r\n\u2022BABY\u00a0 \u00a0 |\u00a0 \u00a0 \u00a015\u20ac\u00a0 \u00a0 \u00a0 |\u00a0 \u00a0 \u00a0 Repas pour les enfants entre 4 et 12 ans\r\n\r\n<strong><b>JE VOUS EXPLIQUE EN VID\u00c9O?\r\n<\/b><\/strong><a href=\"https:\/\/youtu.be\/1tfZ1WoBHaI?si=n2bs6ePs1GIPip7G\" target=\"_blank\" rel=\"noopener\"><span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\u2764\ufe0f<\/span><\/span>\u00a0La box ap\u00e9ro\u00a0\u00a0\u00a0<\/a>\r\n\r\n<a href=\"https:\/\/youtu.be\/1uSA5rxB5t4?si=cx_DAf7Ev2SQxu_V\" target=\"_blank\" rel=\"noopener\"><span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\ud83d\udc67<\/span><\/span>Les boxes pour enfants<\/a>\r\n\r\n\u00a0","_et_gb_content_width":""},"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":["post-5624","product","type-product","status-publish","has-post-thumbnail","product_cat-boites","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/product\/5624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/media\/5625"}],"wp:attachment":[{"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/media?parent=5624"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=5624"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=5624"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lesboitesdebobonne.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=5624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}